{"id":99500,"date":"2020-07-22T10:02:05","date_gmt":"2020-07-22T10:02:05","guid":{"rendered":"https:\/\/essax.es\/?post_type=product&#038;p=99500"},"modified":"2026-05-12T13:40:01","modified_gmt":"2026-05-12T13:40:01","slug":"shark-aleta-s-acero","status":"publish","type":"product","link":"https:\/\/essax.es\/pt\/product\/shark-aleta-s-acero","title":{"rendered":"Sela de tubar\u00e3o \u2013 barbatana S \u2013 FeC \u2013 270 gr."},"content":{"rendered":"<p><strong><a href=\"https:\/\/essax.es\/wp-content\/uploads\/2020\/07\/essax-shark-3-sillin-saddle.jpg\"><img fetchpriority=\"high\" decoding=\"async\" class=\"alignright size-medium wp-image-99480\" src=\"https:\/\/essax.es\/wp-content\/uploads\/2020\/07\/essax-shark-3-sillin-saddle-300x253.jpg\" alt=\"essax-shark-sillin-bike-saddle-fin\" width=\"300\" height=\"253\" srcset=\"https:\/\/essax.es\/wp-content\/uploads\/2020\/07\/essax-shark-3-sillin-saddle-300x253.jpg 300w, https:\/\/essax.es\/wp-content\/uploads\/2020\/07\/essax-shark-3-sillin-saddle-14x12.jpg 14w, https:\/\/essax.es\/wp-content\/uploads\/2020\/07\/essax-shark-3-sillin-saddle-768x648.jpg 768w, https:\/\/essax.es\/wp-content\/uploads\/2020\/07\/essax-shark-3-sillin-saddle-769x649.jpg 769w, https:\/\/essax.es\/wp-content\/uploads\/2020\/07\/essax-shark-3-sillin-saddle-84x71.jpg 84w, https:\/\/essax.es\/wp-content\/uploads\/2020\/07\/essax-shark-3-sillin-saddle-200x169.jpg 200w, https:\/\/essax.es\/wp-content\/uploads\/2020\/07\/essax-shark-3-sillin-saddle-450x380.jpg 450w, https:\/\/essax.es\/wp-content\/uploads\/2020\/07\/essax-shark-3-sillin-saddle.jpg 800w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>Como isso aconteceu?<\/strong><br \/>\nH\u00e1 seis anos a Essax quebrou todos os moldes do setor, mudando a forma de conceber o selim de bicicleta, que n\u00e3o evolu\u00eda h\u00e1 d\u00e9cadas. Lan\u00e7ou um produto completamente novo que criou (e continua a criar) grandes expectativas em todo o mundo. Nunca antes foi feita uma sela como esta, de que todos falam.<\/p>\n<p>Muitos milhares de unidades vendidas depois, e muitos mais ciclistas satisfeitos, provaram que est\u00e1vamos certos e mostraram que n\u00e3o era uma simples extravag\u00e2ncia para chamar a aten\u00e7\u00e3o. O Tubar\u00e3o, funciona.<\/p>\n<p><strong>Para que serve a barbatana?<\/strong><br \/>\n\u00c9 dotado de uma barbatana central, que \u00e9 a chave deste conjunto biomec\u00e2nico. Seu posicionamento informa ao ciclista como posicionar os \u00edsquios para que fiquem perfeitamente apoiados no selim. Quer dizer; Ele interage com o usu\u00e1rio, fornecendo-lhe informa\u00e7\u00f5es sobre como deve sentar-se.<\/p>\n<p>Nas centenas de estudos biomec\u00e2nicos reais realizados durante o desenvolvimento deste produto, as evid\u00eancias disseram-nos que a grande maioria dos ciclistas tinha a percep\u00e7\u00e3o sensorial de estar bem colocados no selim, quando a realidade mostrava que normalmente estavam virados ou apenas apoiados um dos dois \u00edsquios. Porque se tivermos algum tipo de dismetria na vida normal, ela se multiplica na bicicleta, j\u00e1 que a postura adotada para pedalar n\u00e3o \u00e9 natural para o corpo humano.<\/p>\n<p>E se n\u00e3o bastasse, o que inicialmente se pretendia ser uma solu\u00e7\u00e3o terap\u00eautica para o desconforto de milhares de ciclistas, tornou-se num elemento que pode permitir um maior desempenho f\u00edsico, e n\u00e3o porque existe um novo ponto de apoio na bicicleta, que em o facto n\u00e3o \u00e9 tal, mas porque ao dar estabilidade aos quadris, a transmiss\u00e3o de for\u00e7a aos pedais \u00e9 muito mais eficiente, conseguindo assim um maior desempenho.<\/p>\n<p><strong>Est\u00e1 aprovado?<\/strong><br \/>\nO Essax Shark est\u00e1 patenteado, embora a sua utiliza\u00e7\u00e3o em competi\u00e7\u00f5es oficiais da UCI (International Cycling Union) n\u00e3o seja permitida.<\/p>\n<p><strong>Como \u00e9 colocado?<\/strong><br \/>\nEmbora forne\u00e7amos um guia de instala\u00e7\u00e3o, antes de adquiri-lo aconselhamos que consulte primeiro um profissional de biomec\u00e2nica, que o aconselhar\u00e1 sobre a sua correta coloca\u00e7\u00e3o e utiliza\u00e7\u00e3o.<\/p>","protected":false},"excerpt":{"rendered":"<p>A sela que todo mundo est\u00e1 falando. \u00c9 dotado de uma barbatana central, que \u00e9 a chave deste conjunto biomec\u00e2nico. Seu posicionamento informa ao ciclista como posicionar os \u00edsquios para que fiquem perfeitamente apoiados no selim. Quer dizer; Ele interage com o usu\u00e1rio, fornecendo-lhe informa\u00e7\u00f5es sobre como deve sentar-se.<\/p>\n<p><span style=\"font-size: 14pt;\"><strong>Peso: 270 gr.<\/strong><\/span><br \/>\nTrilho: A\u00e7o<\/p>","protected":false},"featured_media":99483,"comment_status":"open","ping_status":"closed","template":"","meta":{"inline_featured_image":false},"product_brand":[],"product_cat":[155],"product_tag":[167,165,166],"class_list":{"0":"post-99500","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-biomecanica","7":"product_tag-aleta","8":"product_tag-shark","9":"product_tag-tiburon","10":"pa_ancho-130-mm","11":"pa_ancho-142-mm","12":"pa_color-negro-negro","13":"pa_color-negro-blanco","14":"pa_rail-acero","16":"first","17":"instock","18":"taxable","19":"shipping-taxable","20":"purchasable","21":"product-type-variable"},"exclude_global_add_ons":[],"addons":[],"_links":{"self":[{"href":"https:\/\/essax.es\/pt\/wp-json\/wp\/v2\/product\/99500"}],"collection":[{"href":"https:\/\/essax.es\/pt\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/essax.es\/pt\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/essax.es\/pt\/wp-json\/wp\/v2\/comments?post=99500"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/essax.es\/pt\/wp-json\/wp\/v2\/media\/99483"}],"wp:attachment":[{"href":"https:\/\/essax.es\/pt\/wp-json\/wp\/v2\/media?parent=99500"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/essax.es\/pt\/wp-json\/wp\/v2\/product_brand?post=99500"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/essax.es\/pt\/wp-json\/wp\/v2\/product_cat?post=99500"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/essax.es\/pt\/wp-json\/wp\/v2\/product_tag?post=99500"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}